{"id":18015,"date":"2024-11-27T15:47:00","date_gmt":"2024-11-27T14:47:00","guid":{"rendered":"https:\/\/rockyourgoal.de\/?p=18015"},"modified":"2024-11-28T15:52:48","modified_gmt":"2024-11-28T14:52:48","slug":"trees4breeze-com-ist-online","status":"publish","type":"post","link":"https:\/\/rockyourgoal.de\/en\/trees4breeze-com-ist-online\/","title":{"rendered":"Trees4Breeze.COM ist online"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Es ist f\u00fcr mich ein weiterer Meilenstein um das gro\u00dfe Ziel zu erreichen, <em>eine Million B\u00e4ume<\/em> aufzuforsten oder zu sch\u00fctzen. Vor ungef\u00e4hr drei Jahren haben wir unter dem Projektnamen &#8222;Trees4Breeze&#8220; gemeinsam damit begonnen, Baumsetzlinge aufzuforsten und W\u00e4lder zu sch\u00fctzen. Aus diesem Antrieb heraus ist die Timeless Challenge (einschlie\u00dflich der Iron Lake Challenge) entstanden \u00fcber deren Einnahmen das Projekt finanziert wird. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nun beginnt die n\u00e4chste Stufe, denn Trees4Breeze hat unter der url <a href=\"https:\/\/trees4breeze.com\/\">trees4breeze.com<\/a> eine eigene Website bekommen. <\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/trees4breeze.com\/\"><img loading=\"lazy\" decoding=\"async\" width=\"689\" height=\"361\" src=\"http:\/\/rockyourgoal.de\/wp-content\/uploads\/2024\/11\/trees4breeze-website.png\" alt=\"\" class=\"wp-image-18016\" srcset=\"https:\/\/rockyourgoal.de\/wp-content\/uploads\/2024\/11\/trees4breeze-website.png 689w, https:\/\/rockyourgoal.de\/wp-content\/uploads\/2024\/11\/trees4breeze-website-300x157.png 300w, https:\/\/rockyourgoal.de\/wp-content\/uploads\/2024\/11\/trees4breeze-website-18x9.png 18w\" sizes=\"auto, (max-width: 689px) 100vw, 689px\" \/><\/a><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Ein Besuch lohnt sich<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Zuk\u00fcnftig wirst Du auf der neuen Seite wertvolle Informationen rund um das Trees4Breeze Projekt finden. Dabei ist es mir besonders wichtig, dass Du zu jedem Zeitpunkt die volle Transparenz hast.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aber Du wirst zuk\u00fcnftig auch sauber recherchierte und fundierte Informationen rund um den Zustand des europ\u00e4ischen Waldes finden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Des Weiteren kannst Du (auch als Geschenk) eine Baumpatenschaft mit einem Baum in dem eigenen Wald eingehen und diesen langfristig sch\u00fctzen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gilt wie immer &#8222;<em>Mal sehen wohin der Weg f\u00fchrt<\/em>&#8222;&#8230;&#8230; Im Moment kenne ich nur die Richtung.<\/p>","protected":false},"excerpt":{"rendered":"<p>Es ist f\u00fcr mich ein weiterer Meilenstein um das gro\u00dfe Ziel zu erreichen, eine Million B\u00e4ume aufzuforsten oder zu sch\u00fctzen. Vor ungef\u00e4hr drei Jahren haben wir unter dem Projektnamen &#8222;Trees4Breeze&#8220; gemeinsam damit begonnen, Baumsetzlinge aufzuforsten und W\u00e4lder zu sch\u00fctzen. Aus diesem Antrieb heraus ist die Timeless Challenge (einschlie\u00dflich der Iron&hellip;<\/p>\n<p> <a class=\"more-link\" href=\"https:\/\/rockyourgoal.de\/en\/trees4breeze-com-ist-online\/\">Read more<\/a><\/p>","protected":false},"author":2,"featured_media":18018,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"pgc_sgb_lightbox_settings":"","_glsr_average":0,"_glsr_ranking":0,"_glsr_reviews":0,"footnotes":""},"categories":[1,11],"tags":[],"class_list":["post-18015","post","type-post","status-publish","format-standard","has-post-thumbnail","category-allgemein","category-trees-for-breeze"],"_links":{"self":[{"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/posts\/18015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/comments?post=18015"}],"version-history":[{"count":5,"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/posts\/18015\/revisions"}],"predecessor-version":[{"id":18025,"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/posts\/18015\/revisions\/18025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/media\/18018"}],"wp:attachment":[{"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/media?parent=18015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/categories?post=18015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rockyourgoal.de\/en\/wp-json\/wp\/v2\/tags?post=18015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}